{"id":40,"count":1,"description":"","link":"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/","name":"sharp","slug":"sharp","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sharp Archives - Stress Codes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sharp Archives - Stress Codes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/\" \/>\n<meta property=\"og:site_name\" content=\"Stress Codes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@stresscodes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/stresscodes.com\\\/index.php\\\/tag\\\/sharp\\\/\",\"url\":\"https:\\\/\\\/stresscodes.com\\\/index.php\\\/tag\\\/sharp\\\/\",\"name\":\"sharp Archives - Stress Codes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stresscodes.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stresscodes.com\\\/index.php\\\/tag\\\/sharp\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stresscodes.com\\\/index.php\\\/tag\\\/sharp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stresscodes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sharp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stresscodes.com\\\/#website\",\"url\":\"https:\\\/\\\/stresscodes.com\\\/\",\"name\":\"Stress Codes\",\"description\":\"Tech Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stresscodes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sharp Archives - Stress Codes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/","og_locale":"en_US","og_type":"article","og_title":"sharp Archives - Stress Codes","og_url":"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/","og_site_name":"Stress Codes","twitter_card":"summary_large_image","twitter_site":"@stresscodes","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/","url":"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/","name":"sharp Archives - Stress Codes","isPartOf":{"@id":"https:\/\/stresscodes.com\/#website"},"breadcrumb":{"@id":"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/stresscodes.com\/index.php\/tag\/sharp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stresscodes.com\/"},{"@type":"ListItem","position":2,"name":"sharp"}]},{"@type":"WebSite","@id":"https:\/\/stresscodes.com\/#website","url":"https:\/\/stresscodes.com\/","name":"Stress Codes","description":"Tech Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stresscodes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/stresscodes.com\/index.php\/wp-json\/wp\/v2\/tags\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stresscodes.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/stresscodes.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/stresscodes.com\/index.php\/wp-json\/wp\/v2\/posts?tags=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}